{"id":81004,"date":"2026-07-15T10:11:53","date_gmt":"2026-07-15T08:11:53","guid":{"rendered":"https:\/\/timewaver.com\/academy\/?post_type=tribe_events&#038;p=81004"},"modified":"2026-07-15T10:15:27","modified_gmt":"2026-07-15T08:15:27","slug":"quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2","status":"publish","type":"tribe_events","link":"https:\/\/timewaver.com\/academy\/zh-hans\/event\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\/","title":{"rendered":"Quantum Longevity \u2013 3-Part Webinar Series with Marcus Schmieke &#8211; Part 2"},"content":{"rendered":"\t\t<div data-elementor-type=\"tec_event_single_static\" data-elementor-id=\"81004\" class=\"elementor elementor-81004\" data-elementor-post-type=\"tribe_events\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13dd42c9 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13dd42c9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-72c9d5c2\" data-id=\"72c9d5c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-658a1b11 elementor-hidden-desktop elementor-widget elementor-widget-image\" data-id=\"658a1b11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"679\" src=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2026\/07\/Marcus-Longevity-2-1024x679.jpg\" class=\"attachment-large size-large wp-image-80947\" alt=\"Marcus Schmieke - Longevity 2\" srcset=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2026\/07\/Marcus-Longevity-2-1024x679.jpg 1024w, https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2026\/07\/Marcus-Longevity-2-300x199.jpg 300w, https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2026\/07\/Marcus-Longevity-2-768x510.jpg 768w, https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2026\/07\/Marcus-Longevity-2-600x398.jpg 600w, https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2026\/07\/Marcus-Longevity-2.jpg 1400w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c18284d elementor-section-content-bottom elementor-hidden-mobile elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c18284d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-10986024\" data-id=\"10986024\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c5288d5 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c5288d5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fd63e02\" data-id=\"fd63e02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-29d109fa elementor-widget elementor-widget-text-editor\" data-id=\"29d109fa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/timewaver.com\/academy\/en\/event-calendar\/\">&lt; All Events<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-750bd595 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"750bd595\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Quantum Longevity \u2013 3-Part Webinar Series with Marcus Schmieke &#8211; Part 2<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-215e89f5 elementor-widget elementor-widget-text-editor\" data-id=\"215e89f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Understanding the Energy Points Module: Structure and Dynamics of the 48 Sub-Life Fields<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5d758b72 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d758b72\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-custom\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2eb46ae8\" data-id=\"2eb46ae8\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3697836 elementor-widget elementor-widget-image\" data-id=\"3697836\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"233\" src=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon1-1.png\" class=\"attachment-large size-large wp-image-17870\" alt=\"TimeWaver Event\" srcset=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon1-1.png 700w, https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon1-1-300x100.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0cd8fe elementor-widget elementor-widget-text-editor\" data-id=\"f0cd8fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-doc-id=\"8985972000009621011\" data-doc-type=\"writer\">Marcus Schmieke, Dr. h.c. (Nobel University, USA)<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-7b4fc868\" data-id=\"7b4fc868\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ed1510d elementor-widget elementor-widget-image\" data-id=\"3ed1510d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"233\" src=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon2-1.png\" class=\"attachment-large size-large wp-image-17872\" alt=\"TimeWaver Event\" srcset=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon2-1.png 700w, https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon2-1-300x100.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51d33d0 elementor-widget elementor-widget-text-editor\" data-id=\"51d33d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>August 26<span data-doc-id=\"5628038000000858027\" data-doc-type=\"writer\">, 2026<\/span><br \/>10:00 &#8211; 11:00 am CEST<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-5f05ece5\" data-id=\"5f05ece5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72083d19 elementor-widget elementor-widget-image\" data-id=\"72083d19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"233\" src=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon3-1.png\" class=\"attachment-large size-large wp-image-17874\" alt=\"TimeWaver Event\" srcset=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon3-1.png 700w, https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon3-1-300x100.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ad90597 elementor-widget elementor-widget-text-editor\" data-id=\"2ad90597\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>TimeWaver Pro, TimeWaver Home, TimeWaver Frequency<br \/><em style=\"font-size: 14px;\">Informational Webinar<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-383ff0c\" data-id=\"383ff0c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-345ed184 elementor-widget elementor-widget-image\" data-id=\"345ed184\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"233\" src=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon4-1.png\" class=\"attachment-large size-large wp-image-17876\" alt=\"TimeWaver Event\" srcset=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon4-1.png 700w, https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon4-1-300x100.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-124a966c elementor-widget elementor-widget-text-editor\" data-id=\"124a966c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Online<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-20 elementor-top-column elementor-element elementor-element-2105735a\" data-id=\"2105735a\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e071588 elementor-widget elementor-widget-image\" data-id=\"6e071588\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"233\" src=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon5-1.png\" class=\"attachment-large size-large wp-image-17878\" alt=\"TimeWaver Event\" srcset=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon5-1.png 700w, https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/08\/Icon5-1-300x100.png 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b842cc4 elementor-widget elementor-widget-text-editor\" data-id=\"7b842cc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Free admission<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d12590 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d12590\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-550d08e\" data-id=\"550d08e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34179d2f elementor-widget elementor-widget-text-editor\" data-id=\"34179d2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4>What to expect in this webinar:<\/h4><p>At the heart of the TimeWaver Quantum Longevity Module is the circular arrangement of the forty-eight sub-life fields. In this second part, you will learn, step by step, how to correctly interpret analysis results in the Information Field and successfully and practically promote your patients\u2019 longevity.<\/p><p>Discover how the circle of the twelve fields of life (\u0398\u2081 to \u0398\u2081\u2082) extends from the physical foundation to inner unity. You\u2019ll learn in an accessible way how each field has four aspects (A to D)\u2014a universal four-part structure that is the same across all twelve fields and makes cross-field pattern recognition possible in the first place. Together with Marcus Schmieke, you\u2019ll delve into the four-part structure and understand which biological bodily function and which subtle-energy foundation is linked to each sub-field.<\/p><p>Sign up now to learn how to use an analysis of the Information Field to pinpoint exactly which sub-fields your clients need support with.<\/p><h4>Webinar Contents:<\/h4><ul><li>The twelve life fields (\u0398\u2081 through \u0398\u2081\u2082) and their arrangement in a circle.<\/li><li>The universal four-part structure of each field: stability, flexibility, exploration, and integration.<\/li><li>Subfields and their biological classification as well as their subtle-energy basis.<\/li><li>How to read an Information Field analysis using the TimeWaver Quantum Longevity Module: The distribution of energy points and the key to the subfields that require attention.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58958d4d elementor-reverse-mobile elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58958d4d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-63a93328\" data-id=\"63a93328\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1140f98f elementor-widget elementor-widget-text-editor\" data-id=\"1140f98f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h4><span data-doc-id=\"8985972000009621011\" data-doc-type=\"writer\">Marcus Schmieke<br \/><\/span><\/h4>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17c5e17d elementor-widget elementor-widget-text-editor\" data-id=\"17c5e17d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Marcus Schmieke is a consciousness researcher, entrepreneur, and the inventor of TimeWaver. The founder of the Existential Consciousness Research Institute (ECR) studied physics and philosophy in Germany and India and, through Information Field Technology, has created a universally applicable synthesis of natural science, spirituality, and philosophy. In addition to his work with TimeWaver, Marcus Schmieke lectures internationally and has published numerous books and scientific papers. His latest work, Quantum Longevity, builds a visionary bridge between modern biophysics and consciousness research, presenting a novel model of self-regulating life.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-17b0f899\" data-id=\"17b0f899\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-382000dc elementor-widget elementor-widget-image\" data-id=\"382000dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"493\" height=\"493\" src=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/12\/Markus_Schmieke_sw-2-4-2-4-2-2-2-1.png\" class=\"attachment-large size-large wp-image-56012\" alt=\"\" srcset=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/12\/Markus_Schmieke_sw-2-4-2-4-2-2-2-1.png 493w, https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/12\/Markus_Schmieke_sw-2-4-2-4-2-2-2-1-300x300.png 300w, https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/12\/Markus_Schmieke_sw-2-4-2-4-2-2-2-1-150x150.png 150w, https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2022\/12\/Markus_Schmieke_sw-2-4-2-4-2-2-2-1-100x100.png 100w\" sizes=\"(max-width: 493px) 100vw, 493px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4b0a1dc7 elementor-reverse-mobile elementor-section-stretched elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b0a1dc7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-24060642\" data-id=\"24060642\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ff8ac35 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"1ff8ac35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.timeanddate.com\/worldclock\/converter.html?iso=20211018T110000&#038;p1=37\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Time zone converter &gt;<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-d5d4461\" data-id=\"d5d4461\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40c6fb35 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40c6fb35\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79e5b99b\" data-id=\"79e5b99b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4343b024 elementor-widget elementor-widget-heading\" data-id=\"4343b024\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Save your seat now without obligation. We are looking forward to meeting you!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-310480b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"310480b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1ddc0f81\" data-id=\"1ddc0f81\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-257e33a1 elementor-widget elementor-widget-heading\" data-id=\"257e33a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Free webinar registration<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e4e0f09 elementor-widget elementor-widget-html\" data-id=\"1e4e0f09\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wj-embed-wrapper\" data-webinar-hash=\"qqm78fqm\">\n<script src=\"https:\/\/event.webinarjam.com\/register\/qqm78fqm\/embed-form?formButtonText=Register&formAccentColor=%2300537f&formAccentOpacity=0.95&formBgColor=%23ffffff&formBgOpacity=1\"><\/script>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>At the heart of the TimeWaver Quantum Longevity Module is the circular arrangement of the forty-eight sub-life fields. In this second part, you will learn, step by step, how to correctly interpret analysis results in the Information Field and successfully and practically promote your patients\u2019 longevity.<\/p>\n","protected":false},"author":2,"featured_media":80942,"template":"","meta":{"_acf_changed":false,"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"disabled","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"disabled","site-post-title":"","ast-breadcrumbs-content":"disabled","ast-featured-img":"disabled","footer-sml-layout":"disabled","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"Tribe__Tickets_Plus__Commerce__WooCommerce__Main","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":"","_tec_slr_enabled":"","_tec_slr_layout":""},"tags":[],"tribe_events_cat":[],"class_list":["post-81004","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quantum Longevity \u2013 3-Part Webinar Series with Marcus Schmieke - Part 2 - TimeWaver Academy<\/title>\n<meta name=\"description\" content=\"At the heart of the TimeWaver Quantum Longevity Module is the circular arrangement of the forty-eight sub-life fields. In this second part, you will learn, step by step, how to correctly interpret analysis results in the Information Field and successfully and practically promote your patients\u2019 longevity.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/timewaver.com\/academy\/zh-hans\/event\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quantum Longevity \u2013 3-Part Webinar Series with Marcus Schmieke - Part 2 - TimeWaver Academy\" \/>\n<meta property=\"og:description\" content=\"At the heart of the TimeWaver Quantum Longevity Module is the circular arrangement of the forty-eight sub-life fields. In this second part, you will learn, step by step, how to correctly interpret analysis results in the Information Field and successfully and practically promote your patients\u2019 longevity.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/timewaver.com\/academy\/zh-hans\/event\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\/\" \/>\n<meta property=\"og:site_name\" content=\"TimeWaver Academy\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T08:15:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2026\/07\/Marcus-Longevity-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"929\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/event\\\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\\\/\",\"url\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/event\\\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\\\/\",\"name\":\"Quantum Longevity \u2013 3-Part Webinar Series with Marcus Schmieke - Part 2 - TimeWaver Academy\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/event\\\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/event\\\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/Marcus-Longevity-2.jpg\",\"datePublished\":\"2026-07-15T08:11:53+00:00\",\"dateModified\":\"2026-07-15T08:15:27+00:00\",\"description\":\"At the heart of the TimeWaver Quantum Longevity Module is the circular arrangement of the forty-eight sub-life fields. In this second part, you will learn, step by step, how to correctly interpret analysis results in the Information Field and successfully and practically promote your patients\u2019 longevity.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/event\\\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/event\\\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/event\\\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/Marcus-Longevity-2.jpg\",\"contentUrl\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2026\\\/07\\\/Marcus-Longevity-2.jpg\",\"width\":1400,\"height\":929,\"caption\":\"Marcus Schmieke - Longevity 2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/event\\\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u6d3b\u52a8\",\"item\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quantum Longevity \u2013 3-Part Webinar Series with Marcus Schmieke &#8211; Part 2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/\",\"name\":\"TimeWaver Academy\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/#organization\",\"name\":\"TimeWaver Academy\",\"url\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/11\\\/TW_Sonderlogo.svg\",\"contentUrl\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2021\\\/11\\\/TW_Sonderlogo.svg\",\"width\":234,\"height\":74,\"caption\":\"TimeWaver Academy\"},\"image\":{\"@id\":\"https:\\\/\\\/timewaver.com\\\/academy\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quantum Longevity \u2013 3-Part Webinar Series with Marcus Schmieke - Part 2 - TimeWaver Academy","description":"At the heart of the TimeWaver Quantum Longevity Module is the circular arrangement of the forty-eight sub-life fields. In this second part, you will learn, step by step, how to correctly interpret analysis results in the Information Field and successfully and practically promote your patients\u2019 longevity.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/timewaver.com\/academy\/zh-hans\/event\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\/","og_locale":"zh_CN","og_type":"article","og_title":"Quantum Longevity \u2013 3-Part Webinar Series with Marcus Schmieke - Part 2 - TimeWaver Academy","og_description":"At the heart of the TimeWaver Quantum Longevity Module is the circular arrangement of the forty-eight sub-life fields. In this second part, you will learn, step by step, how to correctly interpret analysis results in the Information Field and successfully and practically promote your patients\u2019 longevity.","og_url":"https:\/\/timewaver.com\/academy\/zh-hans\/event\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\/","og_site_name":"TimeWaver Academy","article_modified_time":"2026-07-15T08:15:27+00:00","og_image":[{"width":1400,"height":929,"url":"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2026\/07\/Marcus-Longevity-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/timewaver.com\/academy\/zh-hans\/event\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\/","url":"https:\/\/timewaver.com\/academy\/zh-hans\/event\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\/","name":"Quantum Longevity \u2013 3-Part Webinar Series with Marcus Schmieke - Part 2 - TimeWaver Academy","isPartOf":{"@id":"https:\/\/timewaver.com\/academy\/zh-hans\/#website"},"primaryImageOfPage":{"@id":"https:\/\/timewaver.com\/academy\/zh-hans\/event\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\/#primaryimage"},"image":{"@id":"https:\/\/timewaver.com\/academy\/zh-hans\/event\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\/#primaryimage"},"thumbnailUrl":"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2026\/07\/Marcus-Longevity-2.jpg","datePublished":"2026-07-15T08:11:53+00:00","dateModified":"2026-07-15T08:15:27+00:00","description":"At the heart of the TimeWaver Quantum Longevity Module is the circular arrangement of the forty-eight sub-life fields. In this second part, you will learn, step by step, how to correctly interpret analysis results in the Information Field and successfully and practically promote your patients\u2019 longevity.","breadcrumb":{"@id":"https:\/\/timewaver.com\/academy\/zh-hans\/event\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/timewaver.com\/academy\/zh-hans\/event\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\/"]}]},{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/timewaver.com\/academy\/zh-hans\/event\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\/#primaryimage","url":"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2026\/07\/Marcus-Longevity-2.jpg","contentUrl":"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2026\/07\/Marcus-Longevity-2.jpg","width":1400,"height":929,"caption":"Marcus Schmieke - Longevity 2"},{"@type":"BreadcrumbList","@id":"https:\/\/timewaver.com\/academy\/zh-hans\/event\/quantum-longevity-3-part-webinar-series-with-marcus-schmieke-part-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/timewaver.com\/academy\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"\u6d3b\u52a8","item":"https:\/\/timewaver.com\/academy\/zh-hans\/events\/"},{"@type":"ListItem","position":3,"name":"Quantum Longevity \u2013 3-Part Webinar Series with Marcus Schmieke &#8211; Part 2"}]},{"@type":"WebSite","@id":"https:\/\/timewaver.com\/academy\/zh-hans\/#website","url":"https:\/\/timewaver.com\/academy\/zh-hans\/","name":"TimeWaver Academy","description":"","publisher":{"@id":"https:\/\/timewaver.com\/academy\/zh-hans\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/timewaver.com\/academy\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/timewaver.com\/academy\/zh-hans\/#organization","name":"TimeWaver Academy","url":"https:\/\/timewaver.com\/academy\/zh-hans\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/timewaver.com\/academy\/zh-hans\/#\/schema\/logo\/image\/","url":"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2021\/11\/TW_Sonderlogo.svg","contentUrl":"https:\/\/timewaver.com\/academy\/wp-content\/uploads\/sites\/5\/2021\/11\/TW_Sonderlogo.svg","width":234,"height":74,"caption":"TimeWaver Academy"},"image":{"@id":"https:\/\/timewaver.com\/academy\/zh-hans\/#\/schema\/logo\/image\/"}}]}},"ticketed":false,"_links":{"self":[{"href":"https:\/\/timewaver.com\/academy\/zh-hans\/wp-json\/wp\/v2\/tribe_events\/81004","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/timewaver.com\/academy\/zh-hans\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/timewaver.com\/academy\/zh-hans\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/timewaver.com\/academy\/zh-hans\/wp-json\/wp\/v2\/users\/2"}],"version-history":[{"count":3,"href":"https:\/\/timewaver.com\/academy\/zh-hans\/wp-json\/wp\/v2\/tribe_events\/81004\/revisions"}],"predecessor-version":[{"id":81012,"href":"https:\/\/timewaver.com\/academy\/zh-hans\/wp-json\/wp\/v2\/tribe_events\/81004\/revisions\/81012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/timewaver.com\/academy\/zh-hans\/wp-json\/wp\/v2\/media\/80942"}],"wp:attachment":[{"href":"https:\/\/timewaver.com\/academy\/zh-hans\/wp-json\/wp\/v2\/media?parent=81004"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/timewaver.com\/academy\/zh-hans\/wp-json\/wp\/v2\/tags?post=81004"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/timewaver.com\/academy\/zh-hans\/wp-json\/wp\/v2\/tribe_events_cat?post=81004"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}